{"id":43671,"date":"2020-07-20T14:53:05","date_gmt":"2020-07-20T12:53:05","guid":{"rendered":"https:\/\/fermentis.com\/safyeast\/"},"modified":"2026-07-12T18:29:43","modified_gmt":"2026-07-12T16:29:43","slug":"safyeast","status":"publish","type":"page","link":"https:\/\/fermentis.com\/es\/safyeast\/","title":{"rendered":"SafYeast\u2122"},"content":{"rendered":"\n\t<section class=\"section dark has-parallax\" id=\"section_855636825\">\n\t\t<div class=\"section-bg fill\" data-parallax-container=\".section\" data-parallax-background data-parallax=\"-4\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"595\" src=\"https:\/\/fermentis.com\/wp-content\/uploads\/2020\/10\/saf-yeast.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-763833793\">\n\n\t<div id=\"col-1565724751\" class=\"col medium-8 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h6>Nuestra gama de levaduras<\/h6>\n<h1><span style=\"font-size: 200%\">SafYeast\u2122 <\/span><\/h1>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_855636825 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 349px;\n}\n#section_855636825 .section-bg-overlay {\n  background-color: rgba(52, 35, 35, 0.57);\n}\n#section_855636825 .section-bg img {\n  object-position: 0% 100%;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row row-collapse align-right\"  id=\"row-805098080\">\n\n\t<div id=\"col-700718431\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:#4ac193;\" >\n\t\t\t\n\t\t\t\n\n\t<section class=\"section\" id=\"section_1892873503\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-collapse align-center\"  id=\"row-1637314810\">\n\n\t<div id=\"col-413614432\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\"  >\n\t\t\t\n\t\t\t\n<h3><span style=\"font-size: 24.192px\">\u00bfQu\u00e9 es SafYeast\u2122?<br \/><em><br \/>Levadura activa seca Fermentis<\/em><br \/><\/span><\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1637314810 > .col > .col-inner {\n  padding: 40px 20px 20px 20px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1892873503 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  background-color: rgb(239, 117, 0);\n}\n<\/style>\n\t<\/section>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-700718431 > .col-inner {\n  margin: -80px 0px 20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\n\t<section class=\"section\" id=\"section_1999360785\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-185175459\">\n\n\t<div id=\"col-1309239662\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p class=\"lead\">SafYeast\u2122 es una marca utilitaria que cubre todas nuestras cepas de levadura y algunas mezclas de levadura y enzimas.<\/p>\n<p class=\"lead\">El nombre SafYeast\u2122 puede utilizarse en lugar de &quot;levadura activa seca Fermentis&quot;; el significado es el mismo.<\/p>\n<p class=\"lead\">Todos los rangos de productos a continuaci\u00f3n pertenecen a la familia SafYeast\u2122.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1709813407\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1368958317\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"376\" src=\"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/Logo_SafYeast_ByFermentis_RGB-e1695387958886.jpg\" class=\"attachment-large size-large\" alt=\"SafYeast by Fermentis logo\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1368958317 {\n  width: 50%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle\"  id=\"row-1766425629\">\n\n\t<div id=\"col-1404699112\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"row\"  id=\"row-1787090756\">\n\n\t<div id=\"col-1738172112\" class=\"col medium-1 small-6 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-728022473\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"pricing-table-wrapper dark\">\n  <div class=\"pricing-table ux_price_table text-center hide-this box-shadow-3-hover\"style=\"background-color:rgb(235, 175, 92);\">\n    <div class=\"pricing-table-header\">\n      <div class=\"title uppercase strong\">SEGMENTO DE CERVEZAS<\/div>\n      <div class=\"price is-xxlarge\">&nbsp;<\/div>\n          <\/div>\n    <div class=\"pricing-table-items items\">\n      \n<div class=\"bullet-item\" title=\"\"><span class=\"text\">SafAle<\/span><\/div>\n<div class=\"bullet-item\" title=\"\"><span class=\"text\">SafLager\u2122<\/span><\/div>\n<div class=\"bullet-item\" title=\"\"><span class=\"text\">SafBrew\u2122<\/span><\/div>\n    <\/div>\n      <\/div>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-650017981\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"pricing-table-wrapper dark\">\n  <div class=\"pricing-table ux_price_table text-center hide-this box-shadow-3-hover\"style=\"background-color:rgb(173, 41, 51);\">\n    <div class=\"pricing-table-header\">\n      <div class=\"title uppercase strong\">SEGMENTO DE VINOS<\/div>\n      <div class=\"price is-xxlarge\">&nbsp;<\/div>\n          <\/div>\n    <div class=\"pricing-table-items items\">\n      \n<div class=\"bullet-item\" title=\"\"><span class=\"text\">Saf\u0152no\u2122<\/span><\/div>\n    <\/div>\n      <\/div>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1230207443\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"pricing-table-wrapper dark\">\n  <div class=\"pricing-table ux_price_table text-center hide-this box-shadow-3-hover\"style=\"background-color:rgb(20, 86, 127);\">\n    <div class=\"pricing-table-header\">\n      <div class=\"title uppercase strong\">SEGMENTO DE DESTILADOS<\/div>\n      <div class=\"price is-xxlarge\">&nbsp;<\/div>\n          <\/div>\n    <div class=\"pricing-table-items items\">\n      \n<div class=\"bullet-item\" title=\"\"><span class=\"text\">SafSpirit\u2122<\/span><\/div>\n<div class=\"bullet-item\" title=\"\"><span class=\"text\">SafTeq\u2122<\/span><\/div>\n    <\/div>\n      <\/div>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1202040833\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"pricing-table-wrapper dark\">\n  <div class=\"pricing-table ux_price_table text-center hide-this box-shadow-3-hover\"style=\"background-color:rgb(169, 192, 103);\">\n    <div class=\"pricing-table-header\">\n      <div class=\"title uppercase strong\">SEGMENTO DE SIDRAS<\/div>\n      <div class=\"price is-xxlarge\">&nbsp;<\/div>\n          <\/div>\n    <div class=\"pricing-table-items items\">\n      \n<div class=\"bullet-item\" title=\"\"><span class=\"text\">SafCider\u2122<\/span><\/div>\n    <\/div>\n      <\/div>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1224897233\" class=\"col medium-2 small-6 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"pricing-table-wrapper dark\">\n  <div class=\"pricing-table ux_price_table text-center hide-this box-shadow-3-hover\"style=\"background-color:rgb(172, 172, 172);\">\n    <div class=\"pricing-table-header\">\n      <div class=\"title uppercase strong\">OTRAS BEBIDAS<\/div>\n      <div class=\"price is-xxlarge\">&nbsp;<\/div>\n          <\/div>\n    <div class=\"pricing-table-items items\">\n      \n<div class=\"bullet-item\" title=\"\"><span class=\"text\">SafSorghum\u2122<\/span><\/div>\n<div class=\"bullet-item\" title=\"\"><span class=\"text\">SafKvas\u2122<\/span><\/div>\n    <\/div>\n      <\/div>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-577548753\" class=\"col medium-1 small-6 large-1\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1620651884\">\n\n\t<div id=\"col-872700785\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe loading=\"lazy\" title=\"10 reasons to use Fermentis active dry yeast - Introducing SafYeast\u2122\" width=\"1020\" height=\"574\" src=\"https:\/\/www.youtube.com\/embed\/UqAu9voX-Ok?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1999360785 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-43671","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SafYeast\u2122 - Fermentis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fermentis.com\/es\/safyeast\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SafYeast\u2122\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fermentis.com\/es\/safyeast\/\" \/>\n<meta property=\"og:site_name\" content=\"Fermentis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fermentis\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-12T16:29:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/website-v2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1903\" \/>\n\t<meta property=\"og:image:height\" content=\"901\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fermentis\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/safyeast\\\/\",\"url\":\"https:\\\/\\\/fermentis.com\\\/es\\\/safyeast\\\/\",\"name\":\"SafYeast\u2122 - Fermentis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#website\"},\"datePublished\":\"2020-07-20T12:53:05+00:00\",\"dateModified\":\"2026-07-12T16:29:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/safyeast\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fermentis.com\\\/es\\\/safyeast\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/safyeast\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fermentis.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SafYeast\u2122\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fermentis.com\\\/es\\\/\",\"name\":\"Fermentis\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fermentis.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#organization\",\"name\":\"Fermentis\",\"url\":\"https:\\\/\\\/fermentis.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fermentis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-Fermentis-5.png\",\"contentUrl\":\"https:\\\/\\\/fermentis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-Fermentis-5.png\",\"width\":308,\"height\":95,\"caption\":\"Fermentis\"},\"image\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fermentis\",\"https:\\\/\\\/x.com\\\/fermentis\",\"https:\\\/\\\/www.instagram.com\\\/fermentisbylesaffre\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fermentis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt_Lp3IZnUNXZeqSi6iiAdA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SafYeast\u2122 - Fermentis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fermentis.com\/es\/safyeast\/","og_locale":"es_ES","og_type":"article","og_title":"SafYeast\u2122","og_url":"https:\/\/fermentis.com\/es\/safyeast\/","og_site_name":"Fermentis","article_publisher":"https:\/\/www.facebook.com\/Fermentis","article_modified_time":"2026-07-12T16:29:43+00:00","og_image":[{"width":1903,"height":901,"url":"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/website-v2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@fermentis","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fermentis.com\/es\/safyeast\/","url":"https:\/\/fermentis.com\/es\/safyeast\/","name":"SafYeast\u2122 - Fermentis","isPartOf":{"@id":"https:\/\/fermentis.com\/es\/#website"},"datePublished":"2020-07-20T12:53:05+00:00","dateModified":"2026-07-12T16:29:43+00:00","breadcrumb":{"@id":"https:\/\/fermentis.com\/es\/safyeast\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fermentis.com\/es\/safyeast\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fermentis.com\/es\/safyeast\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fermentis.com\/es\/"},{"@type":"ListItem","position":2,"name":"SafYeast\u2122"}]},{"@type":"WebSite","@id":"https:\/\/fermentis.com\/es\/#website","url":"https:\/\/fermentis.com\/es\/","name":"Fermentis","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/fermentis.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fermentis.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fermentis.com\/es\/#organization","name":"Fermentis","url":"https:\/\/fermentis.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fermentis.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/Logo-Fermentis-5.png","contentUrl":"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/Logo-Fermentis-5.png","width":308,"height":95,"caption":"Fermentis"},"image":{"@id":"https:\/\/fermentis.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fermentis","https:\/\/x.com\/fermentis","https:\/\/www.instagram.com\/fermentisbylesaffre\/","https:\/\/www.linkedin.com\/company\/fermentis\/","https:\/\/www.youtube.com\/channel\/UCt_Lp3IZnUNXZeqSi6iiAdA"]}]}},"_links":{"self":[{"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/pages\/43671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/comments?post=43671"}],"version-history":[{"count":2140,"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/pages\/43671\/revisions"}],"predecessor-version":[{"id":747881,"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/pages\/43671\/revisions\/747881"}],"wp:attachment":[{"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/media?parent=43671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}