{"id":41749,"date":"2024-07-26T16:11:33","date_gmt":"2024-07-26T14:11:33","guid":{"rendered":"https:\/\/fermentis.com\/product\/safale-s%e2%80%9133\/"},"modified":"2026-08-31T23:51:54","modified_gmt":"2026-08-31T21:51:54","slug":"safale-s-33","status":"publish","type":"product","link":"https:\/\/fermentis.com\/es\/producto\/safale-s-33\/","title":{"rendered":"SafAle\u2122 S-33"},"content":{"rendered":"<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:115%;\">Levadura ideal para potenciar perfiles lupulados y afrutados en cervezas ale<\/span><b aria-hidden=\"true\"><\/b><\/h2><\/div>\n<p>Cepa con perfil afrutado, que eleva la sensaci\u00f3n en boca y provee cuerpo a las cervezas. Ideal para las estilos ales belgas (estilos Blond, Dubbel, Tripel, Quadrupel) y las ales inglesas fuertes (ej. Imperial Stouts). Tambi\u00e9n es ideal para New England IPAs. Levadura de sedimentaci\u00f3n media: no forma grumos, sino una neblina pulverulenta cuando se resuspende en la cerveza.<\/p>\n<p><strong>Ingredientes:<\/strong> Levadura<em> (Saccharomyces cerevisiae<\/em>), emulsionante E491<\/p>\n\t<div id=\"gap-2021902493\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2021902493 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:115%;\">Descripci\u00f3n general de SAFALE\u2122 S-33<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<div class=\"row\"  id=\"row-990805215\">\n\n\t<div id=\"col-1703962457\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>\u00c9steres<br \/>\ntotales<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-637640871\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1183556679\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">Medio<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1183556679 {\n  width: 60%;\n}\n#text-box-1183556679 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-637640871 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1703962457 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-24746255\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Alcoholes superiores totales<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-1948327267\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-391759742\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">Medio<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-391759742 {\n  width: 60%;\n}\n#text-box-391759742 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1948327267 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-24746255 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-856286956\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Atenuaci\u00f3n aparente<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-960601758\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-928793156\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">68-72%<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-928793156 {\n  width: 60%;\n}\n#text-box-928793156 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-960601758 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-856286956 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-820892025\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Tiempo de sedimentaci\u00f3n<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-742575849\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-316011554\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">Medio<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-316011554 {\n  width: 60%;\n}\n#text-box-316011554 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-742575849 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-820892025 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-101820984\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Tolerancia al alcohol<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-1043471306\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-989497004\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">9-11%<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-989497004 {\n  width: 60%;\n}\n#text-box-989497004 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1043471306 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-101820984 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2046390939\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Expresi\u00f3n fen\u00f3lica (POF+)<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-803851347\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1495778263\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1495778263 {\n  width: 60%;\n}\n#text-box-1495778263 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-803851347 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2046390939 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-941880281\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-941880281 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:115%;\">Caracter\u00edsticas t\u00e9cnicas de SAFALE\u2122 S-33<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n\t\t<div class=\"tabbed-content\">\n\t\t\t\n\t\t\t<ul class=\"nav nav-tabs nav-uppercase nav-size-normal nav-left\" role=\"tablist\"><li id=\"tab-dosificaci\u00f3n-y-modo-de-empleo\" class=\"tab active has-icon\" role=\"presentation\"><a href=\"#tab_dosificaci\u00f3n-y-modo-de-empleo\" role=\"tab\" aria-selected=\"true\" aria-controls=\"tab_dosificaci\u00f3n-y-modo-de-empleo\"><span>Dosificaci\u00f3n y modo de empleo<\/span><\/a><\/li>\n<li id=\"tab-an\u00e1lisis-t\u00edpico\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_an\u00e1lisis-t\u00edpico\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_an\u00e1lisis-t\u00edpico\"><span>An\u00e1lisis t\u00edpico<\/span><\/a><\/li>\n<li id=\"tab-almacenamiento-y-vida-\u00fatil\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_almacenamiento-y-vida-\u00fatil\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_almacenamiento-y-vida-\u00fatil\"><span>Almacenamiento y vida \u00fatil<\/span><\/a><\/li><\/ul><div class=\"tab-panels\"><div id=\"tab_dosificaci\u00f3n-y-modo-de-empleo\" class=\"panel active entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-dosificaci\u00f3n-y-modo-de-empleo\">\n<h4><span style=\"font-size: 18pt\">Dosis \/ Temperatura<\/span><\/h4>\n<p><strong>50 a 80 g\/hl, idealmente a 18-26 \u00b0C (64,4-78,8 \u00b0F).<\/strong><\/p>\n<h5>Utilice<\/h5>\n<p>Los conocimientos t\u00e9cnicos de Lesaffre y la mejora continua del proceso de producci\u00f3n de levaduras generan una calidad excepcional de levaduras secas capaces de resistir a una gama muy amplia de usos, incluidas condiciones de rehidrataci\u00f3n en fr\u00edo o sin rehidrataci\u00f3n, sin que ello afecte a su viabilidad, cin\u00e9tica y\/o perfil anal\u00edtico. Los cerveceros pueden elegir las condiciones de uso que mejor se adapten a sus necesidades, es decir<\/p>\n<p><strong>\u2460 Inoculazione diretta:<\/strong><\/p>\n<p>Siembre la levadura directamente en el recipiente de fermentaci\u00f3n sobre la superficie del mosto a la temperatura de fermentaci\u00f3n o por encima de ella. Espolvorear progresivamente la levadura seca en el mosto asegur\u00e1ndose de que la levadura cubra toda la superficie de mosto disponible para evitar grumos. Lo ideal es que la levadura se a\u00f1ada durante la primera parte del llenado del recipiente, en cuyo caso la hidrataci\u00f3n puede realizarse a una temperatura del mosto superior a la de fermentaci\u00f3n, llen\u00e1ndose a continuaci\u00f3n el fermentador con mosto a una temperatura inferior para que todo el mosto alcance la temperatura de fermentaci\u00f3n.<\/p>\n<p><strong>\u2461 Con rehidrataci\u00f3n previa:<\/strong><\/p>\n<p>Alternativamente, espolvorear la levadura en un m\u00ednimo de 10 veces su peso de agua est\u00e9ril o mosto hervido y lupulado a 25 a 29\u00b0C (77\u00b0F a 84\u00b0F). Dejar reposar de 15 a 30 minutos, remover suavemente y echar la crema resultante en el recipiente de fermentaci\u00f3n.<\/p>\n<\/div>\n<div id=\"tab_an\u00e1lisis-t\u00edpico\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-an\u00e1lisis-t\u00edpico\">\n<ul>\n<li>Levaduras viables &gt; 1,0 * 10<sup>10<\/sup>UFC\/g<\/li>\n<li>Pureza: &gt; 99,9%\n<ul>\n<li>Bacterias l\u00e1cticas: &lt; 1 UFC\/10<sup>7<\/sup> c\u00e9lulas de levadura<\/li>\n<li>Bacterias ac\u00e9ticas: &lt; 1 UFC\/10<sup>7<\/sup> c\u00e9lulas de levadura<\/li>\n<li>Pediococcus: &lt; 1 UFC\/10<sup>7<\/sup> c\u00e9lulas de levadura<\/li>\n<li>Bacterias totales: &lt; 5 UFC\/10<sup>7<\/sup> c\u00e9lulas de levadura<\/li>\n<li>Levadura &quot;savajes&quot;*: &lt; 1 UFC\/10<sup>7<\/sup> c\u00e9lulas de levadura<\/li>\n<li>Microorganismos pat\u00f3genos: de conformidad con la normativa<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><em>*EBC Analytica 4.2.6 &#8211; ASBC Control Microbiol\u00f3gico-5D<\/em><\/p>\n<\/div>\n<div id=\"tab_almacenamiento-y-vida-\u00fatil\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-almacenamiento-y-vida-\u00fatil\">\n<h4>Almacenamiento<\/h4>\n<p>Para menos de 6 meses: el producto debe almacenarse a menos de 24\u00b0C. Durante m\u00e1s de 6 meses: el producto debe almacenarse a menos de 15\u00b0C. Para periodos cortos no superiores a 7 d\u00edas existe una excepci\u00f3n a estas normas.<\/p>\n<h4>Caducidad<\/h4>\n<p>36 meses a partir de la fecha de producci\u00f3n. Consultar la fecha de caducidad impresa en el empaque. Los paquetes abiertos deben sellarse y conservarse a 4 \u00b0C (39 \u00b0F), y usarse dentro de los 7 d\u00edas posteriores a la apertura. No utilice paquetes blandos o da\u00f1ados.<\/p>\n<p><em>Cada levadura Fermentis se desarrolla seg\u00fan un esquema de producci\u00f3n espec\u00edfico y se beneficia de los conocimientos t\u00e9cnicos del grupo Lesaffre, l\u00edder mundial en la fabricaci\u00f3n de levaduras. Esto garantiza la m\u00e1xima pureza microbiol\u00f3gica y la m\u00e1xima actividad de fermentaci\u00f3n.<\/em><\/p>\n<\/div><\/div><\/div>\n\t<div id=\"gap-328487983\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-328487983 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<p><em>Las levaduras secas para cerveza de Fermentis son reconocidas por su capacidad de producir una amplia variedad de estilos de cerveza. Para comparar nuestras cepas realizamos pruebas de fermentaci\u00f3n en condiciones de laboratorio con mosto est\u00e1ndar y condiciones de temperatura t\u00edpicas (SafLager\u2122: 14 \u00b0C -SafAle\u2122: 20 \u00b0C). Nos enfocamos en los siguientes par\u00e1metros: producci\u00f3n de alcohol, az\u00facares residuales, floculaci\u00f3n y cin\u00e9tica de fermentaci\u00f3n. Dado el impacto de la levadura en la calidad final de la cerveza, se recomienda respetar las instrucciones de fermentaci\u00f3n. Sugerimos realizar pruebas de fermentaci\u00f3n antes de cualquier uso comercial de nuestros productos.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Levadura ideal para potenciar perfiles lupulados y afrutados en cervezas ale<\/p>\n","protected":false},"featured_media":737675,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1355,1356],"product_tag":[1808,1809],"class_list":["post-41749","product","type-product","status-publish","has-post-thumbnail","product_cat-active-dry-yeast-es","product_cat-beer-brewing-solutions-es","product_tag-s-33-es","product_tag-s33-es","pa_alcohol-tolerance-10-es","pa_alcohol-tolerance-11-es","pa_alcohol-tolerance-9-es","pa_apparent-attenuation-68-es","pa_apparent-attenuation-69-es","pa_apparent-attenuation-70-es","pa_apparent-attenuation-71-es","pa_apparent-attenuation-72-es","pa_beer-style-american-british-ales-es","pa_beer-style-barley-wines-es","pa_beer-style-belgian-strong-ales-es","pa_beer-style-brut-ipas-es","pa_beer-style-hazy-ipas-es","pa_beer-style-session-ipas-es","pa_beer-style-stout-es","pa_sedimentation-medium-es","pa_total-esters-medium-es","pa_total-superior-alcohols-medium-es","pa_yeast-range-safale-es","pa_yeast-variety-saccharomyces-cerevisiae-es","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SafAle\u2122 S-33 - Levadura ale para elaborar cervezas afrutadas y lupuladas - Fermentis<\/title>\n<meta name=\"description\" content=\"La levadura SafAle\u2122 S-33 de Fermentis es ideal para elaborar cervezas Belgian Ales y Strong English Ales, pero tambi\u00e9n puede adaptarse a otros estilos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fermentis.com\/es\/producto\/safale-s-33\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SafAle\u2122 S-33\" \/>\n<meta property=\"og:description\" content=\"La levadura SafAle\u2122 S-33 de Fermentis es ideal para elaborar cervezas Belgian Ales y Strong English Ales, pero tambi\u00e9n puede adaptarse a otros estilos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fermentis.com\/es\/producto\/safale-s-33\/\" \/>\n<meta property=\"og:site_name\" content=\"Fermentis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fermentis\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T21:51:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/cnc7b94pkjfm9z2cqf5sw89\/SafAleTM_S-33_All_.jpg?auto=webp&format=png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fermentis\" \/>\n<meta name=\"twitter:label1\" content=\"Precio\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilidad\" \/>\n\t<meta name=\"twitter:data2\" content=\"Disponible\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/producto\\\/safale-s-33\\\/\",\"url\":\"https:\\\/\\\/fermentis.com\\\/es\\\/producto\\\/safale-s-33\\\/\",\"name\":\"SafAle\u2122 S-33 - Levadura ale para elaborar cervezas afrutadas y lupuladas - Fermentis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/producto\\\/safale-s-33\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/producto\\\/safale-s-33\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.bfldr.com\\\/G7S7MSWL\\\/at\\\/cnc7b94pkjfm9z2cqf5sw89\\\/SafAleTM_S-33_All_.jpg?auto=webp&format=png\",\"datePublished\":\"2024-07-26T14:11:33+00:00\",\"dateModified\":\"2026-08-31T21:51:54+00:00\",\"description\":\"La levadura SafAle\u2122 S-33 de Fermentis es ideal para elaborar cervezas Belgian Ales y Strong English Ales, pero tambi\u00e9n puede adaptarse a otros estilos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/producto\\\/safale-s-33\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fermentis.com\\\/es\\\/producto\\\/safale-s-33\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/producto\\\/safale-s-33\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.bfldr.com\\\/G7S7MSWL\\\/at\\\/cnc7b94pkjfm9z2cqf5sw89\\\/SafAleTM_S-33_All_.jpg?auto=webp&format=png\",\"contentUrl\":\"https:\\\/\\\/cdn.bfldr.com\\\/G7S7MSWL\\\/at\\\/cnc7b94pkjfm9z2cqf5sw89\\\/SafAleTM_S-33_All_.jpg?auto=webp&format=png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/producto\\\/safale-s-33\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fermentis.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Soluciones para cerveza y elaboraci\u00f3n\",\"item\":\"https:\\\/\\\/fermentis.com\\\/es\\\/fermentation\\\/beer-brewing-solutions-es\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Levadura cervecera seca activa\",\"item\":\"https:\\\/\\\/fermentis.com\\\/es\\\/fermentation\\\/beer-brewing-solutions-es\\\/active-dry-yeast-es\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"SafAle\u2122 S-33\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fermentis.com\\\/es\\\/\",\"name\":\"Fermentis\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fermentis.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#organization\",\"name\":\"Fermentis\",\"url\":\"https:\\\/\\\/fermentis.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fermentis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-Fermentis-5.png\",\"contentUrl\":\"https:\\\/\\\/fermentis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-Fermentis-5.png\",\"width\":308,\"height\":95,\"caption\":\"Fermentis\"},\"image\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fermentis\",\"https:\\\/\\\/x.com\\\/fermentis\",\"https:\\\/\\\/www.instagram.com\\\/fermentisbylesaffre\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fermentis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt_Lp3IZnUNXZeqSi6iiAdA\"]}]}<\/script>\n<meta property=\"product:price:currency\" content=\"GBP\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SafAle\u2122 S-33 - Levadura ale para elaborar cervezas afrutadas y lupuladas - Fermentis","description":"La levadura SafAle\u2122 S-33 de Fermentis es ideal para elaborar cervezas Belgian Ales y Strong English Ales, pero tambi\u00e9n puede adaptarse a otros estilos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fermentis.com\/es\/producto\/safale-s-33\/","og_locale":"es_ES","og_type":"article","og_title":"SafAle\u2122 S-33","og_description":"La levadura SafAle\u2122 S-33 de Fermentis es ideal para elaborar cervezas Belgian Ales y Strong English Ales, pero tambi\u00e9n puede adaptarse a otros estilos.","og_url":"https:\/\/fermentis.com\/es\/producto\/safale-s-33\/","og_site_name":"Fermentis","article_publisher":"https:\/\/www.facebook.com\/Fermentis","article_modified_time":"2026-08-31T21:51:54+00:00","og_image":[{"url":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/cnc7b94pkjfm9z2cqf5sw89\/SafAleTM_S-33_All_.jpg?auto=webp&format=png","width":1024,"height":1024,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@fermentis","twitter_misc":{"Precio":"","Disponibilidad":"Disponible"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fermentis.com\/es\/producto\/safale-s-33\/","url":"https:\/\/fermentis.com\/es\/producto\/safale-s-33\/","name":"SafAle\u2122 S-33 - Levadura ale para elaborar cervezas afrutadas y lupuladas - Fermentis","isPartOf":{"@id":"https:\/\/fermentis.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fermentis.com\/es\/producto\/safale-s-33\/#primaryimage"},"image":{"@id":"https:\/\/fermentis.com\/es\/producto\/safale-s-33\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/cnc7b94pkjfm9z2cqf5sw89\/SafAleTM_S-33_All_.jpg?auto=webp&format=png","datePublished":"2024-07-26T14:11:33+00:00","dateModified":"2026-08-31T21:51:54+00:00","description":"La levadura SafAle\u2122 S-33 de Fermentis es ideal para elaborar cervezas Belgian Ales y Strong English Ales, pero tambi\u00e9n puede adaptarse a otros estilos.","breadcrumb":{"@id":"https:\/\/fermentis.com\/es\/producto\/safale-s-33\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fermentis.com\/es\/producto\/safale-s-33\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fermentis.com\/es\/producto\/safale-s-33\/#primaryimage","url":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/cnc7b94pkjfm9z2cqf5sw89\/SafAleTM_S-33_All_.jpg?auto=webp&format=png","contentUrl":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/cnc7b94pkjfm9z2cqf5sw89\/SafAleTM_S-33_All_.jpg?auto=webp&format=png"},{"@type":"BreadcrumbList","@id":"https:\/\/fermentis.com\/es\/producto\/safale-s-33\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fermentis.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productos"},{"@type":"ListItem","position":3,"name":"Soluciones para cerveza y elaboraci\u00f3n","item":"https:\/\/fermentis.com\/es\/fermentation\/beer-brewing-solutions-es\/"},{"@type":"ListItem","position":4,"name":"Levadura cervecera seca activa","item":"https:\/\/fermentis.com\/es\/fermentation\/beer-brewing-solutions-es\/active-dry-yeast-es\/"},{"@type":"ListItem","position":5,"name":"SafAle\u2122 S-33"}]},{"@type":"WebSite","@id":"https:\/\/fermentis.com\/es\/#website","url":"https:\/\/fermentis.com\/es\/","name":"Fermentis","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/fermentis.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fermentis.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fermentis.com\/es\/#organization","name":"Fermentis","url":"https:\/\/fermentis.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fermentis.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/Logo-Fermentis-5.png","contentUrl":"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/Logo-Fermentis-5.png","width":308,"height":95,"caption":"Fermentis"},"image":{"@id":"https:\/\/fermentis.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fermentis","https:\/\/x.com\/fermentis","https:\/\/www.instagram.com\/fermentisbylesaffre\/","https:\/\/www.linkedin.com\/company\/fermentis\/","https:\/\/www.youtube.com\/channel\/UCt_Lp3IZnUNXZeqSi6iiAdA"]}]},"product_price_currency":"GBP","og_availability":"instock","product_availability":"instock","product_condition":"new"},"fifu_image_url":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/cnc7b94pkjfm9z2cqf5sw89\/SafAleTM_S-33_All_.jpg?auto=webp&format=png","_links":{"self":[{"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/product\/41749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/comments?post=41749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/media\/737675"}],"wp:attachment":[{"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/media?parent=41749"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/product_brand?post=41749"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/product_cat?post=41749"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/product_tag?post=41749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}