{"id":1501,"count":11,"description":"","link":"https:\/\/fermentis.com\/es\/fermentation\/active-dry-yeast-es\/safale-es-2\/","name":"SafAle\u2122","slug":"safale-es-2","taxonomy":"product_cat","parent":1355,"meta":[],"menu_order":6,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Archives des SafAle\u2122 - Fermentis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fermentis.com\/es\/fermentation\/active-dry-yeast-es\/safale-es-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SafAle\u2122 Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fermentis.com\/es\/fermentation\/active-dry-yeast-es\/safale-es-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Fermentis\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/website-v2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1903\" \/>\n\t<meta property=\"og:image:height\" content=\"901\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fermentis\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/fermentation\\\/active-dry-yeast-es\\\/safale-es-2\\\/\",\"url\":\"https:\\\/\\\/fermentis.com\\\/es\\\/fermentation\\\/active-dry-yeast-es\\\/safale-es-2\\\/\",\"name\":\"Archives des SafAle\u2122 - Fermentis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/fermentation\\\/active-dry-yeast-es\\\/safale-es-2\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/fermentation\\\/active-dry-yeast-es\\\/safale-es-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fermentis.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cerveza con levadura seca activa\",\"item\":\"https:\\\/\\\/fermentis.com\\\/es\\\/fermentation\\\/active-dry-yeast-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SafAle\u2122\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fermentis.com\\\/es\\\/\",\"name\":\"Fermentis\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fermentis.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#organization\",\"name\":\"Fermentis\",\"url\":\"https:\\\/\\\/fermentis.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fermentis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-Fermentis-5.png\",\"contentUrl\":\"https:\\\/\\\/fermentis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-Fermentis-5.png\",\"width\":308,\"height\":95,\"caption\":\"Fermentis\"},\"image\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fermentis\",\"https:\\\/\\\/x.com\\\/fermentis\",\"https:\\\/\\\/www.instagram.com\\\/fermentisbylesaffre\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fermentis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt_Lp3IZnUNXZeqSi6iiAdA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Archives des SafAle\u2122 - Fermentis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fermentis.com\/es\/fermentation\/active-dry-yeast-es\/safale-es-2\/","og_locale":"es_ES","og_type":"article","og_title":"SafAle\u2122 Archives","og_url":"https:\/\/fermentis.com\/es\/fermentation\/active-dry-yeast-es\/safale-es-2\/","og_site_name":"Fermentis","og_image":[{"width":1903,"height":901,"url":"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/website-v2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@fermentis","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fermentis.com\/es\/fermentation\/active-dry-yeast-es\/safale-es-2\/","url":"https:\/\/fermentis.com\/es\/fermentation\/active-dry-yeast-es\/safale-es-2\/","name":"Archives des SafAle\u2122 - Fermentis","isPartOf":{"@id":"https:\/\/fermentis.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/fermentis.com\/es\/fermentation\/active-dry-yeast-es\/safale-es-2\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/fermentis.com\/es\/fermentation\/active-dry-yeast-es\/safale-es-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fermentis.com\/es\/"},{"@type":"ListItem","position":2,"name":"Cerveza con levadura seca activa","item":"https:\/\/fermentis.com\/es\/fermentation\/active-dry-yeast-es\/"},{"@type":"ListItem","position":3,"name":"SafAle\u2122"}]},{"@type":"WebSite","@id":"https:\/\/fermentis.com\/es\/#website","url":"https:\/\/fermentis.com\/es\/","name":"Fermentis","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/fermentis.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fermentis.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fermentis.com\/es\/#organization","name":"Fermentis","url":"https:\/\/fermentis.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fermentis.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/Logo-Fermentis-5.png","contentUrl":"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/Logo-Fermentis-5.png","width":308,"height":95,"caption":"Fermentis"},"image":{"@id":"https:\/\/fermentis.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fermentis","https:\/\/x.com\/fermentis","https:\/\/www.instagram.com\/fermentisbylesaffre\/","https:\/\/www.linkedin.com\/company\/fermentis\/","https:\/\/www.youtube.com\/channel\/UCt_Lp3IZnUNXZeqSi6iiAdA"]}]}},"_links":{"self":[{"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/product_cat\/1501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/product_cat\/1355"}],"wp:post_type":[{"href":"https:\/\/fermentis.com\/es\/wp-json\/wp\/v2\/product?product_cat=1501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}