{"id":41723,"date":"2024-07-30T12:11:02","date_gmt":"2024-07-30T10:11:02","guid":{"rendered":"https:\/\/fermentis.com\/product\/safale-be%e2%80%91256\/"},"modified":"2026-08-31T19:01:08","modified_gmt":"2026-08-31T17:01:08","slug":"safale-be-256","status":"publish","type":"product","link":"https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/","title":{"rendered":"SafAle\u2122 BE-256"},"content":{"rendered":"<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:115%;\">Il celeberrimo lievito per le birre Strong Ale<\/span><b aria-hidden=\"true\"><\/b><\/h2><\/div>\n<p>Lievito secco attivo consigliato per la fermentazione di diverse birre di tipo belga, come lo stile Abbaye, noto per il suo sapore fruttato e l&#039;alto contenuto alcolico. Fermenta molto velocemente e rivela intensi aromi fermentativi. Per mantenere il profilo aromatico a fine fermentazione, si consiglia di raccogliere questo lievito il prima possibile dopo la fermentazione.<\/p>\n<p><strong>Ingredienti:<\/strong> lievito (<em>Saccharomyces cerevisiae<\/em>), emulsionante E491<\/p>\n\t<div id=\"gap-265938827\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-265938827 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:115%;\">Generalit\u00e0 - SafAle\u2122 BE-256<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n\t<section class=\"section\" id=\"section_266921060\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 1px 1px 1px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1495518767\">\n\n\t<div id=\"col-1339317265\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Esteri<br \/>\ntotali<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-1153520600\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1810457152\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">Alto<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1810457152 {\n  width: 60%;\n}\n#text-box-1810457152 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1153520600 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1339317265 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1977529005\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Totale alcoli superiori<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-353936400\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1799436280\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">Alto<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1799436280 {\n  width: 60%;\n}\n#text-box-1799436280 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-353936400 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1977529005 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-990797613\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Attenuazione apparente<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-362214203\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-863535334\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">82%-86%<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-863535334 {\n  width: 60%;\n}\n#text-box-863535334 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-362214203 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-990797613 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1567734658\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Tempo di sedimentazione<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-207569365\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-738305568\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">Veloce<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-738305568 {\n  width: 60%;\n}\n#text-box-738305568 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-207569365 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1567734658 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1652727322\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Tolleranza all&#039;alcool<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-1619862416\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-23520163\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">9%-11%<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-23520163 {\n  width: 60%;\n}\n#text-box-23520163 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1619862416 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1652727322 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-90309376\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Note fenoliche<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-856883834\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-235596438\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">&#8211;<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-235596438 {\n  width: 60%;\n}\n#text-box-235596438 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-856883834 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-90309376 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_266921060 {\n  padding-top: 10px;\n  padding-bottom: 10px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-2043136334\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2043136334 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:115%;\">SafAle\u2122 BE-256 Profilo sensoriale<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1542907038\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"473\" src=\"https:\/\/fermentis.com\/wp-content\/uploads\/2022\/02\/Sensory-Profile-SafAle\u2122-BE-256-1-1024x475.png\" class=\"attachment-large size-large\" alt=\"Sensory Profile SafAle\u2122 BE-256\" srcset=\"https:\/\/fermentis.com\/wp-content\/uploads\/2022\/02\/Sensory-Profile-SafAle\u2122-BE-256-1-1024x475.png 1024w, https:\/\/fermentis.com\/wp-content\/uploads\/2022\/02\/Sensory-Profile-SafAle\u2122-BE-256-1-800x371.png 800w, https:\/\/fermentis.com\/wp-content\/uploads\/2022\/02\/Sensory-Profile-SafAle\u2122-BE-256-1-768x356.png 768w, https:\/\/fermentis.com\/wp-content\/uploads\/2022\/02\/Sensory-Profile-SafAle\u2122-BE-256-1-1536x712.png 1536w, https:\/\/fermentis.com\/wp-content\/uploads\/2022\/02\/Sensory-Profile-SafAle\u2122-BE-256-1-2048x950.png 2048w, https:\/\/fermentis.com\/wp-content\/uploads\/2022\/02\/Sensory-Profile-SafAle\u2122-BE-256-1-600x278.png 600w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1542907038 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<p>SafAle\u2122 BE-256 conferisce aromi fruttati in diverse condizioni di fermentazione, in particolare a densit\u00e0 elevate e temperature di fermentazione elevate.<\/p>\n<p>Questo lievito \u00e8 ideale per produrre birre belghe forti e ricche di sapore.<\/p>\n\t<div id=\"gap-1080085271\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1080085271 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:115%;\">Caratteristiche tecniche - SafAle\u2122 BE-256<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n\t\t<div class=\"tabbed-content\">\n\t\t\t\n\t\t\t<ul class=\"nav nav-tabs nav-uppercase nav-size-normal nav-left\" role=\"tablist\"><li id=\"tab-dosaggio-e-utilizzo\" class=\"tab active has-icon\" role=\"presentation\"><a href=\"#tab_dosaggio-e-utilizzo\" role=\"tab\" aria-selected=\"true\" aria-controls=\"tab_dosaggio-e-utilizzo\"><span>Dosaggio e utilizzo<\/span><\/a><\/li>\n<li id=\"tab-cinetica\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_cinetica\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_cinetica\"><span>Cinetica<\/span><\/a><\/li>\n<li id=\"tab-analisi-tipica\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_analisi-tipica\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_analisi-tipica\"><span>Analisi tipica<\/span><\/a><\/li>\n<li id=\"tab-conservazione;-scadenza\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_conservazione;-scadenza\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_conservazione;-scadenza\"><span>Conservazione; scadenza<\/span><\/a><\/li><\/ul><div class=\"tab-panels\"><div id=\"tab_dosaggio-e-utilizzo\" class=\"panel active entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-dosaggio-e-utilizzo\">\n<h4><span style=\"font-size: 18pt\">Dosaggio\/Temperatura<\/span><\/h4>\n<p><span style=\"font-size: 120%\"><strong>Da 50 a 80 g\/hl ad una temperatura ideale di 18\u00b0-26\u00b0C<\/strong><\/span><\/p>\n<h5>Utilizzo<\/h5>\n<p>Il know-how di Lesaffre e il continuo miglioramento del processo di produzione del lievito generano una qualit\u00e0 eccezionale di lieviti secchi in grado di resistere a un&#039;ampia gamma di utilizzi, comprese le condizioni di reidratazione a freddo o senza, senza compromettere la vitalit\u00e0, il profilo cinetico e\/o analitico. I produttori di birra possono scegliere le condizioni di utilizzo pi\u00f9 adatte alle loro esigenze, ad es:<\/p>\n<p><strong>\u2460 Inoculaci\u00f3n directa:<\/strong><\/p>\n<p>Porre il lievito direttamente nel recipiente di fermentazione sulla superficie del mosto a una temperatura pari o superiore a quella di fermentazione. Cospargere progressivamente il lievito secco nel mosto assicurandosi che il lievito copra tutta la superficie del mosto disponibile per evitare grumi. Idealmente, il lievito viene aggiunto durante la prima parte del riempimento del recipiente; in questo caso l&#039;idratazione pu\u00f2 avvenire a una temperatura del mosto superiore a quella di fermentazione, mentre il fermentatore viene poi riempito con mosto a temperatura inferiore per portare l&#039;intera temperatura del mosto a quella di fermentazione.<\/p>\n<p><strong>\u2461 Con reidratazione preventiva:<\/strong><\/p>\n<p>In alternativa, cospargere il lievito in almeno 10 volte il suo peso di acqua sterile o di mosto bollito e luppolato a 25-29\u00b0C (77\u00b0F-84\u00b0F). Lasciare riposare da 15 a 30 minuti, mescolare delicatamente e versare la crema ottenuta nel recipiente di fermentazione.<\/p>\n<\/div>\n<div id=\"tab_cinetica\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-cinetica\">\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1458741615\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"733\" height=\"354\" src=\"https:\/\/fermentis.com\/wp-content\/uploads\/2022\/02\/\u200cKinetics-SafAle\u2122-BE-256.png\" class=\"attachment-large size-large\" alt=\"\u200cKinetics SafAle\u2122 BE-256\" srcset=\"https:\/\/fermentis.com\/wp-content\/uploads\/2022\/02\/\u200cKinetics-SafAle\u2122-BE-256.png 733w, https:\/\/fermentis.com\/wp-content\/uploads\/2022\/02\/\u200cKinetics-SafAle\u2122-BE-256-600x290.png 600w\" sizes=\"auto, (max-width: 733px) 100vw, 733px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1458741615 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n<\/div>\n<div id=\"tab_analisi-tipica\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-analisi-tipica\">\n<ul>\n<li>Lievito vitale &gt; 1,0 *10<sup>10 <\/sup>ufc\/g<\/li>\n<li>Purezza: &gt; 99,9<\/li>\n<ul>\n<li>Batteri lattici: &lt; 1 ufc \/10<sup>7<\/sup> cellule di lievito<\/li>\n<li>Batteri dell&#039;acido acetico: &lt; 1 ufc \/10<sup>7<\/sup> cellule di lievito<\/li>\n<li>Pediococcus: &lt; 1 ufc \/10<sup>7<\/sup> cellule di lievito<\/li>\n<li>Batteri totali: &lt; 5 ufc \/10<sup>7<\/sup> cellule di lievito<\/li>\n<li>Lievito &quot;selvatico &quot;*: &lt; 1 ufc \/10<sup>7<\/sup> cellule di lievito<\/li>\n<li>Microrganismi patogeni: in conformit\u00e0 al regolamento<\/li>\n<\/ul>\n<\/ul>\n<p><em>*EBC Analytica 4.2.6 &#8211; ASBC Controllo Microbiologico-5D<\/em><\/p>\n<\/div>\n<div id=\"tab_conservazione;-scadenza\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-conservazione;-scadenza\">\n<h4>Immagazzinamento<\/h4>\n<p>Per meno di 6 mesi: il prodotto deve essere conservato a meno di 24\u00b0C. Per pi\u00f9 di 6 mesi: il prodotto deve essere conservato a meno di 15\u00b0C. Per brevi periodi non superiori a 7 giorni \u00e8 prevista un&#039;eccezione a queste regole.<\/p>\n<h4>Durata di conservazione<\/h4>\n<p>36 mesi dalla data di produzione. Le confezioni aperte devono essere ermeticamente sigillate e conservate a massimo 4\u00b0C e utilizzate entro 7 giorni dall&#039;apertura. Non utilizzare le confezioni che hanno perso il sottovuoto.<\/p>\n<p><em>Ogni lievito Fermentis \u00e8 sviluppato secondo uno specifico schema di produzione e beneficia del know-how del gruppo Lesaffre, leader mondiale nella produzione di lieviti. Ci\u00f2 garantisce la massima purezza microbiologica e la massima attivit\u00e0 di fermentazione.<\/em><\/p>\n<\/div><\/div><\/div>\n\t<div id=\"gap-1556258533\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1556258533 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<p><em>I lieviti secchi Fermentis sono noti per la loro capacit\u00e0 di produrre una grande variet\u00e0 di stili di birra. Per confrontare i nostri ceppi, abbiamo eseguito prove di fermentazione in condizioni di laboratorio con un mosto standard per tutti i ceppi e condizioni di temperatura standard (SafLager: 12\u00b0C per 48h poi 14\u00b0C \/ SafAle: 20\u00b0C). Ci siamo concentrati sui seguenti parametri: Produzione di alcol, zuccheri residui, flocculazione e cinetica di fermentazione. Dato l&#039;impatto del lievito sulla qualit\u00e0 della birra finale, si raccomanda di rispettare le istruzioni di fermentazione consigliate. Consigliamo vivamente agli utenti di effettuare prove di fermentazione prima di qualsiasi utilizzo commerciale dei nostri prodotti.<\/em><\/p>\n\t<div id=\"gap-1598991699\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1598991699 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:115%;\">Contenuti correlati<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n  \n    <div id=\"row-1115884666\" class=\"row large-columns-3 medium-columns-1 small-columns-1 has-shadow row-box-shadow-2 row-masonry\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il celeberrimo lievito per le birre Strong Ale<\/p>\n","protected":false},"featured_media":737908,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1359,1358],"product_tag":[1643,1644],"class_list":["post-41723","product","type-product","status-publish","has-post-thumbnail","product_cat-beer-brewing-solutions-it","product_cat-active-dry-yeast-it","product_tag-be-256-it","product_tag-be256-it","pa_alcohol-tolerance-10-it","pa_alcohol-tolerance-11-it","pa_alcohol-tolerance-12-it","pa_alcohol-tolerance-13-it","pa_alcohol-tolerance-9-it","pa_apparent-attenuation-82-it","pa_apparent-attenuation-83-it","pa_apparent-attenuation-84-it","pa_apparent-attenuation-85-it","pa_apparent-attenuation-86-it","pa_beer-style-american-british-ales-it","pa_beer-style-barley-wines-it","pa_beer-style-belgian-strong-ales-it","pa_beer-style-imperial-porters-stouts-it","pa_beer-style-porter-it","pa_fermentation-temperature-15-it","pa_fermentation-temperature-16-it","pa_fermentation-temperature-17-it","pa_fermentation-temperature-18-it","pa_fermentation-temperature-19-it","pa_fermentation-temperature-20-it","pa_phenolic-off-flavor-negative-it","pa_sedimentation-fast-it","pa_total-esters-high-it","pa_total-superior-alcohols-high-it","pa_yeast-range-safale-it","pa_yeast-variety-saccharomyces-cerevisiae-it","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SafAle\u2122 BE-256 - Lievito di birra per birre in stile belga e Abbaye - Fermentis<\/title>\n<meta name=\"description\" content=\"Il lievito Fermentis SafAle BE-256 \u00e8 ideale per produrre birre in stile Abbaye belga con note fruttate e alto contenuto alcolico, o altri stili di birra.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SafAle\u2122 BE-256\" \/>\n<meta property=\"og:description\" content=\"Il lievito Fermentis SafAle BE-256 \u00e8 ideale per produrre birre in stile Abbaye belga con note fruttate e alto contenuto alcolico, o altri stili di birra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/\" \/>\n<meta property=\"og:site_name\" content=\"Fermentis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fermentis\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T17:01:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/rbh824rchtbj93vx5g3x9qkc\/SafAleTM_BE-256_All_.jpg?auto=webp&format=png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fermentis\" \/>\n<meta name=\"twitter:label1\" content=\"Prezzo\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/safale-be-256\\\/\",\"url\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/safale-be-256\\\/\",\"name\":\"SafAle\u2122 BE-256 - Lievito di birra per birre in stile belga e Abbaye - Fermentis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/safale-be-256\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/safale-be-256\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.bfldr.com\\\/G7S7MSWL\\\/at\\\/rbh824rchtbj93vx5g3x9qkc\\\/SafAleTM_BE-256_All_.jpg?auto=webp&format=png\",\"datePublished\":\"2024-07-30T10:11:02+00:00\",\"dateModified\":\"2026-08-31T17:01:08+00:00\",\"description\":\"Il lievito Fermentis SafAle BE-256 \u00e8 ideale per produrre birre in stile Abbaye belga con note fruttate e alto contenuto alcolico, o altri stili di birra.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/safale-be-256\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/safale-be-256\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/safale-be-256\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.bfldr.com\\\/G7S7MSWL\\\/at\\\/rbh824rchtbj93vx5g3x9qkc\\\/SafAleTM_BE-256_All_.jpg?auto=webp&format=png\",\"contentUrl\":\"https:\\\/\\\/cdn.bfldr.com\\\/G7S7MSWL\\\/at\\\/rbh824rchtbj93vx5g3x9qkc\\\/SafAleTM_BE-256_All_.jpg?auto=webp&format=png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/safale-be-256\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fermentis.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beer &amp; brewing solutions\",\"item\":\"https:\\\/\\\/fermentis.com\\\/it\\\/fermentation\\\/beer-brewing-solutions-it\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Birra con lievito secco attivo\",\"item\":\"https:\\\/\\\/fermentis.com\\\/it\\\/fermentation\\\/beer-brewing-solutions-it\\\/active-dry-yeast-it\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"SafAle\u2122 BE-256\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/fermentis.com\\\/it\\\/\",\"name\":\"Fermentis\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fermentis.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/#organization\",\"name\":\"Fermentis\",\"url\":\"https:\\\/\\\/fermentis.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fermentis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-Fermentis-5.png\",\"contentUrl\":\"https:\\\/\\\/fermentis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-Fermentis-5.png\",\"width\":308,\"height\":95,\"caption\":\"Fermentis\"},\"image\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fermentis\",\"https:\\\/\\\/x.com\\\/fermentis\",\"https:\\\/\\\/www.instagram.com\\\/fermentisbylesaffre\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fermentis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt_Lp3IZnUNXZeqSi6iiAdA\"]}]}<\/script>\n<meta property=\"product:price:currency\" content=\"GBP\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SafAle\u2122 BE-256 - Lievito di birra per birre in stile belga e Abbaye - Fermentis","description":"Il lievito Fermentis SafAle BE-256 \u00e8 ideale per produrre birre in stile Abbaye belga con note fruttate e alto contenuto alcolico, o altri stili di birra.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/","og_locale":"it_IT","og_type":"article","og_title":"SafAle\u2122 BE-256","og_description":"Il lievito Fermentis SafAle BE-256 \u00e8 ideale per produrre birre in stile Abbaye belga con note fruttate e alto contenuto alcolico, o altri stili di birra.","og_url":"https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/","og_site_name":"Fermentis","article_publisher":"https:\/\/www.facebook.com\/Fermentis","article_modified_time":"2026-08-31T17:01:08+00:00","og_image":[{"url":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/rbh824rchtbj93vx5g3x9qkc\/SafAleTM_BE-256_All_.jpg?auto=webp&format=png","width":1024,"height":1024,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@fermentis","twitter_misc":{"Prezzo":"","Disponibilit\u00e0":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/","url":"https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/","name":"SafAle\u2122 BE-256 - Lievito di birra per birre in stile belga e Abbaye - Fermentis","isPartOf":{"@id":"https:\/\/fermentis.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/#primaryimage"},"image":{"@id":"https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/rbh824rchtbj93vx5g3x9qkc\/SafAleTM_BE-256_All_.jpg?auto=webp&format=png","datePublished":"2024-07-30T10:11:02+00:00","dateModified":"2026-08-31T17:01:08+00:00","description":"Il lievito Fermentis SafAle BE-256 \u00e8 ideale per produrre birre in stile Abbaye belga con note fruttate e alto contenuto alcolico, o altri stili di birra.","breadcrumb":{"@id":"https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/#primaryimage","url":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/rbh824rchtbj93vx5g3x9qkc\/SafAleTM_BE-256_All_.jpg?auto=webp&format=png","contentUrl":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/rbh824rchtbj93vx5g3x9qkc\/SafAleTM_BE-256_All_.jpg?auto=webp&format=png"},{"@type":"BreadcrumbList","@id":"https:\/\/fermentis.com\/it\/prodotto\/safale-be-256\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fermentis.com\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti"},{"@type":"ListItem","position":3,"name":"Beer &amp; brewing solutions","item":"https:\/\/fermentis.com\/it\/fermentation\/beer-brewing-solutions-it\/"},{"@type":"ListItem","position":4,"name":"Birra con lievito secco attivo","item":"https:\/\/fermentis.com\/it\/fermentation\/beer-brewing-solutions-it\/active-dry-yeast-it\/"},{"@type":"ListItem","position":5,"name":"SafAle\u2122 BE-256"}]},{"@type":"WebSite","@id":"https:\/\/fermentis.com\/it\/#website","url":"https:\/\/fermentis.com\/it\/","name":"Fermentis","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/fermentis.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fermentis.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/fermentis.com\/it\/#organization","name":"Fermentis","url":"https:\/\/fermentis.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fermentis.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/Logo-Fermentis-5.png","contentUrl":"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/Logo-Fermentis-5.png","width":308,"height":95,"caption":"Fermentis"},"image":{"@id":"https:\/\/fermentis.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fermentis","https:\/\/x.com\/fermentis","https:\/\/www.instagram.com\/fermentisbylesaffre\/","https:\/\/www.linkedin.com\/company\/fermentis\/","https:\/\/www.youtube.com\/channel\/UCt_Lp3IZnUNXZeqSi6iiAdA"]}]},"product_price_currency":"GBP","og_availability":"instock","product_availability":"instock","product_condition":"new"},"fifu_image_url":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/rbh824rchtbj93vx5g3x9qkc\/SafAleTM_BE-256_All_.jpg?auto=webp&format=png","_links":{"self":[{"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/product\/41723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/comments?post=41723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/media\/737908"}],"wp:attachment":[{"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/media?parent=41723"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/product_brand?post=41723"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/product_cat?post=41723"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/product_tag?post=41723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}