{"id":41729,"date":"2024-07-30T10:29:41","date_gmt":"2024-07-30T08:29:41","guid":{"rendered":"https:\/\/fermentis.com\/product\/saflager-w%e2%80%9134-70\/"},"modified":"2026-09-02T15:51:59","modified_gmt":"2026-09-02T13:51:59","slug":"saflager-w-34-70","status":"publish","type":"product","link":"https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/","title":{"rendered":"SafLager\u2122 W-34\/70"},"content":{"rendered":"<div class=\"container section-title-container\" ><h2 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:115%;\">Il lievito forte e robusto per lager, ideale per birre neutre<\/span><b aria-hidden=\"true\"><\/b><\/h2><\/div>\n<p>Questo celeberrimo ceppo di lievito di birra proveniente da Weihenstephan, Germania, \u00e8 utilizzato in tutti i birrifici del mondo. SafLager\u2122 W-34\/70 permette di produrre birre con un buon equilibrio tra aromi fiorali e fruttati, d\u00e0 sapori franchi e birre altamente beverine.<\/p>\n<p><strong><\/strong>Ingredienti: lievito (<em>Saccharomyces pastorianus<\/em>), emulsionante E491<\/p>\n<div class=\"row row-small\"  id=\"row-1819425278\">\n\n\t<div id=\"col-28246083\" class=\"col ppage-visible small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-28246083 > .col-inner {\n  margin: 0px 0px -20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1819425278 > .col > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n<\/style>\n<\/div>\n\t<div id=\"gap-2126060156\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2126060156 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:115%;\">Generalit\u00e0 - SafLager\u2122 W-34\/70<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n\t<section class=\"section\" id=\"section_1756812831\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 1px 1px 1px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-427443505\">\n\n\t<div id=\"col-1114373149\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong><br \/>\nTotale<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-823830865\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-881832332\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">Bassi<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-881832332 {\n  width: 60%;\n}\n#text-box-881832332 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-823830865 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1114373149 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2027419584\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Totale alcoli superiori<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-539004937\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-822091936\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">Bassi<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-822091936 {\n  width: 60%;\n}\n#text-box-822091936 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-539004937 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2027419584 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1267103499\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Attenuazione apparente<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-652423658\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-694092797\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">80-84%<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-694092797 {\n  width: 60%;\n}\n#text-box-694092797 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-652423658 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1267103499 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-342700606\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Tempo di sedimentazione<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-106479377\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-2037667813\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">Veloce<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-2037667813 {\n  width: 60%;\n}\n#text-box-2037667813 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-106479377 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-342700606 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-117607655\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Tolleranza all&#039;alcool<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-124800798\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1024961987\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">9-11% vol.<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1024961987 {\n  width: 60%;\n}\n#text-box-1024961987 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-124800798 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-117607655 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-924194993\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: center\"><span style=\"font-size: 100%\"><strong>Note fenoliche<\/strong><\/span><\/p>\n\n  <div class=\"banner has-hover round-corners\" id=\"banner-19762461\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-425007116\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<p style=\"text-align: center\"><span style=\"font-size: 120%;color: #333333\">&#8211;<\/span><\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-425007116 {\n  width: 60%;\n}\n#text-box-425007116 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-19762461 {\n  padding-top: 99.99%;\n  background-color: rgb(239, 194, 126);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-924194993 > .col-inner {\n  padding: 5px 5px 5px 5px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1756812831 {\n  padding-top: 10px;\n  padding-bottom: 10px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-1069846663\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1069846663 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:115%;\">Caratteristiche tecniche - SafLager\u2122 W-34\/70<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n\t\t<div class=\"tabbed-content\">\n\t\t\t\n\t\t\t<ul class=\"nav nav-tabs nav-uppercase nav-size-normal nav-left\" role=\"tablist\"><li id=\"tab-dosaggio-e-utilizzo\" class=\"tab active has-icon\" role=\"presentation\"><a href=\"#tab_dosaggio-e-utilizzo\" role=\"tab\" aria-selected=\"true\" aria-controls=\"tab_dosaggio-e-utilizzo\"><span>Dosaggio e utilizzo<\/span><\/a><\/li>\n<li id=\"tab-analisi-tipica\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_analisi-tipica\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_analisi-tipica\"><span>Analisi tipica<\/span><\/a><\/li>\n<li id=\"tab-conservazione-e-durata-di-conservazione\" class=\"tab has-icon\" role=\"presentation\"><a href=\"#tab_conservazione-e-durata-di-conservazione\" tabindex=\"-1\" role=\"tab\" aria-selected=\"false\" aria-controls=\"tab_conservazione-e-durata-di-conservazione\"><span>Conservazione e durata di conservazione<\/span><\/a><\/li><\/ul><div class=\"tab-panels\"><div id=\"tab_dosaggio-e-utilizzo\" class=\"panel active entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-dosaggio-e-utilizzo\">\n<h4><span style=\"font-size: 18pt\">Dosaggio \/ Temperatura<\/span><\/h4>\n<p><strong>Da 80 a 120 g\/hl ad una temperatura ideale di 12\u00b0-18\u00b0C.<\/strong><\/p>\n<h5>Utilizzo<\/h5>\n<p>Il savoir-faire di Lesaffre e il continuo miglioramento del processo di produzione del lievito consentono di ottenere una qualit\u00e0 eccezionale di lieviti secchi in grado di resistere ad un&#039;ampia gamma di utilizzo, compresa la reidratazione a freddo o l&#039;inoculo diretto, senza compromettere la vitalit\u00e0, il profilo cinetico e\/o analitico dei lieviti stessi. I produttori di birra possono scegliere le condizioni di utilizzo che meglio si adattano alle loro esigenze, ad es:<\/p>\n<p><strong>\u2460 Inoculo diretto:<\/strong><\/p>\n<p>Inoculare il lievito direttamente nel recipiente di fermentazione sulla superficie del mosto ad una temperatura pari o superiore a quella di fermentazione. Disperdere poco il lievito secco nel mosto assicurandosi che il lievito copra tutta la superficie del mosto per evitare la formazione di grumi. Idealmente, il lievito viene aggiunto durante la prima parte del riempimento del fermentatore; in questo caso la reidratazione pu\u00f2 avvenire ad una temperatura di mosto superiore a quella di fermentazione, il fermentatore sar\u00e0 poi riempito con mosto ad una temperatura inferiore per portare l&#039;intera massa di mosto alla temperatura di fermentazione.<\/p>\n<p><strong>\u2461 Previa reidratazione:<\/strong><\/p>\n<p>In alternativa, disperdere il lievito in almeno 10 volte il suo peso di acqua sterile o di mosto bollito e luppolato a 15\u00b0-25\u00b0C. Lasciare riposare da 15 a 30 minuti, mescolare delicatamente e versare la crema ottenuta nel recipiente di fermentazione.<\/p>\n<\/div>\n<div id=\"tab_analisi-tipica\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-analisi-tipica\">\n<ul>\n<li>Lievito vivo &gt; 6,0\u00d710<sup>9 <\/sup>ufc\/g<\/li>\n<li>Purezza: &gt; 99,9%\n<ul>\n<li>Batteri lattici: &lt; 1 ufc \/6,0\u00d710<sup>6<\/sup> cellule di lievito<\/li>\n<li>Batteri acetici: &lt; 1 ufc \/6,0\u00d710<sup>6<\/sup> cellule di lievito<\/li>\n<li>Pediococcus: &lt; 1 ufc \/6,0\u00d710<sup>6<\/sup> cellule di lievito<\/li>\n<li>Batteri totali: &lt; 1 ufc\/10<sup>6<\/sup> cellule di lievito<\/li>\n<li>Lievito &quot;selvaggio &quot;*: &lt; 1 ufc \/6*10<sup>6<\/sup> cellule di lievito<\/li>\n<li>Microrganismi patogeni: in conformit\u00e0 con la normativa<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><em>*EBC Analytica 4.2.6 \u2013 ASBC Microbiological Control-5D<\/em><\/p>\n<\/div>\n<div id=\"tab_conservazione-e-durata-di-conservazione\" class=\"panel entry-content\" role=\"tabpanel\" aria-labelledby=\"tab-conservazione-e-durata-di-conservazione\">\n<h4>Conservazione<\/h4>\n<p>Per massimo 6 mesi: il prodotto deve essere conservato a massimo 24\u00b0C. Per pi\u00f9 di 6 mesi: il prodotto deve essere conservato a massimo 15\u00b0C. Per brevi periodi non superiori a 7 giorni \u00e8 prevista un&#039;eccezione a queste regole.<\/p>\n<h4>Durata di conservazione<\/h4>\n<p>36 mesi dalla data di produzione. Le confezioni aperte devono essere ermeticamente sigillate e conservate a massimo 4\u00b0C e utilizzate entro 7 giorni dall&#039;apertura. Non utilizzare le confezioni che hanno perso il sottovuoto.<\/p>\n<p><em>Ogni lievito Fermentis \u00e8 sviluppato secondo uno specifico schema di produzione e si avvale del savoir-faire del gruppo Lesaffre, leader mondiale nella produzione di lieviti. Ci\u00f2 garantisce la massima purezza microbiologica e la massima attivit\u00e0 di fermentazione.<\/em><\/p>\n<\/div><\/div><\/div>\n\t<div id=\"gap-1294759625\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1294759625 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<p><em>I lieviti per birra secchi Fermentis sono celebri per la loro capacit\u00e0 di produrre un&#039;ampia variet\u00e0 di stili di birra. Per confrontare i nostri ceppi, abbiamo eseguito prove di fermentazione per tutti i ceppi in condizioni di laboratorio con un mosto standard e condizioni di temperatura standard (SafLager: 12\u00b0C per 48h poi 14\u00b0C \/ SafAle: 20\u00b0C). Ci siamo concentrati sui seguenti parametri: produzione di alcool, zuccheri residui, flocculazione e cinetica di fermentazione. Dato l&#039;impatto del lievito sulla qualit\u00e0 della birra finale, si raccomanda di rispettare le istruzioni di fermentazione prescritte. Consigliamo vivamente gli utilizzatori\u00a0di effettuare prove\u00a0di fermentazione prima\u00a0di qualsiasi utilizzo commerciale\u00a0dei nostri prodotti.\u00a0<\/em><\/p>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >Contenuti correlati<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-3 medium-columns-1 small-columns-1 slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/fermentis.com\/it\/news\/testimonials\/brewer-stories-puesto-saflager-w-34-70-mexican-lagers\/\" class=\"plain\" aria-label=\"Storie di birrai: produzione di lager messicane di fama mondiale con SafLager\u2122 W-34\/70 presso Puesto Cervecer\u00eda\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"209\" src=\"https:\/\/fermentis.com\/wp-content\/uploads\/2026\/02\/Fermentis-blog-cover-4-800x209.avif\" class=\"attachment-medium size-medium not-transparent wp-post-image\" alt=\"Storie di birrai: produzione di lager messicane di fama mondiale con SafLager\u2122 W-34\/70 presso Puesto Cervecer\u00eda\" title=\"Storie di birrai: produzione di lager messicane di fama mondiale con SafLager\u2122 W-34\/70 presso Puesto Cervecer\u00eda\" srcset=\"https:\/\/fermentis.com\/wp-content\/uploads\/2026\/02\/Fermentis-blog-cover-4-800x209.avif 800w, https:\/\/fermentis.com\/wp-content\/uploads\/2026\/02\/Fermentis-blog-cover-4-1024x267.avif 1024w, https:\/\/fermentis.com\/wp-content\/uploads\/2026\/02\/Fermentis-blog-cover-4-768x200.avif 768w, https:\/\/fermentis.com\/wp-content\/uploads\/2026\/02\/Fermentis-blog-cover-4-600x157.avif 600w, https:\/\/fermentis.com\/wp-content\/uploads\/2026\/02\/Fermentis-blog-cover-4.avif 1150w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" data-has-transparency=\"false\" data-dominant-color=\"343940\" style=\"--dominant-color: #343940;\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/fermentis.com\/it\/news\/testimonials\/brewer-stories-puesto-saflager-w-34-70-mexican-lagers\/\" class=\"plain\">Storie di birrai: produzione di lager messicane di fama mondiale con SafLager\u2122 W-34\/70 presso Puesto Cervecer\u00eda<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tElaborare una lager perfetta richiede tempo, pazienza e abilit\u00e0. Con alle spalle 35 anni di...\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">02<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Mar<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56.25%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/fermentis.com\/it\/news\/testimonials\/brewer-stories-highland-park-brewery-saflager-w-34-70\/\" class=\"plain\" aria-label=\"Storie di birrai: come il birrificio Highland Park ha vinto due medaglie d&#8217;oro al GABF utilizzando un solo lievito Lager\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"209\" src=\"https:\/\/fermentis.com\/wp-content\/uploads\/2026\/02\/Fermentis-blog-cover-2-800x209.avif\" class=\"attachment-medium size-medium not-transparent wp-post-image\" alt=\"Storie di birrai: come il birrificio Highland Park ha vinto due medaglie d&#8217;oro al GABF utilizzando un solo lievito Lager\" title=\"Storie di birrai: come il birrificio Highland Park ha vinto due medaglie d&#8217;oro al GABF utilizzando un solo lievito Lager\" srcset=\"https:\/\/fermentis.com\/wp-content\/uploads\/2026\/02\/Fermentis-blog-cover-2-800x209.avif 800w, https:\/\/fermentis.com\/wp-content\/uploads\/2026\/02\/Fermentis-blog-cover-2-1024x267.avif 1024w, https:\/\/fermentis.com\/wp-content\/uploads\/2026\/02\/Fermentis-blog-cover-2-768x200.avif 768w, https:\/\/fermentis.com\/wp-content\/uploads\/2026\/02\/Fermentis-blog-cover-2-600x157.avif 600w, https:\/\/fermentis.com\/wp-content\/uploads\/2026\/02\/Fermentis-blog-cover-2.avif 1150w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" data-has-transparency=\"false\" data-dominant-color=\"404044\" style=\"--dominant-color: #404044;\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">\n\t\t\t\t\t\t<a href=\"https:\/\/fermentis.com\/it\/news\/testimonials\/brewer-stories-highland-park-brewery-saflager-w-34-70\/\" class=\"plain\">Storie di birrai: come il birrificio Highland Park ha vinto due medaglie d&#8217;oro al GABF utilizzando un solo lievito Lager<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">\n\t\t\t\t\t\tPer le nostre ultime Storie di birrai abbiamo visitato il birrificio Highland Park di Los...\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-outline\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">10<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Gen<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il lievito forte e robusto per lager, ideale per birre neutre<\/p>\n","protected":false},"featured_media":738068,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1359,1358],"product_tag":[1704,1705,1706,1707,1708],"class_list":["post-41729","product","type-product","status-publish","has-post-thumbnail","product_cat-beer-brewing-solutions-it","product_cat-active-dry-yeast-it","product_tag-34-70-it","product_tag-w-34-70-it","product_tag-w-3470-it","product_tag-w34-70-it","product_tag-w3470-it","pa_alcohol-tolerance-10-it","pa_alcohol-tolerance-11-it","pa_alcohol-tolerance-9-it","pa_apparent-attenuation-80-it","pa_apparent-attenuation-81-it","pa_apparent-attenuation-82-it","pa_apparent-attenuation-83-it","pa_apparent-attenuation-84-it","pa_beer-style-pils-and-special-lager-it","pa_fermentation-temperature-12-it","pa_fermentation-temperature-13-it","pa_fermentation-temperature-14-it","pa_fermentation-temperature-15-it","pa_phenolic-off-flavor-negative-it","pa_sedimentation-fast-it","pa_total-esters-low-it","pa_total-superior-alcohols-low-it","pa_yeast-range-saflager-it","pa_yeast-variety-saccharomyces-pastorianus-it","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SafLager\u2122 W-34\/70 - lievito Fermentis per birre dallo stile Weihenstephan<\/title>\n<meta name=\"description\" content=\"Il lievito Fermentis SafLager\u2122 W-34\/70 \u00e8 ideale per la produzione di birre Weihenstephan, ma si adatta ad altri stili di birra, buon divertimento!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SafLager\u2122 W-34\/70\" \/>\n<meta property=\"og:description\" content=\"Il lievito Fermentis SafLager\u2122 W-34\/70 \u00e8 ideale per la produzione di birre Weihenstephan, ma si adatta ad altri stili di birra, buon divertimento!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/\" \/>\n<meta property=\"og:site_name\" content=\"Fermentis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fermentis\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T13:51:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/gzfvmgnhv7xwk8kh7xcct9k4\/SafAleTM_W-34-70-134_All_.jpg?auto=webp&format=png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fermentis\" \/>\n<meta name=\"twitter:label1\" content=\"Prezzo\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e0\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/saflager-w-34-70\\\/\",\"url\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/saflager-w-34-70\\\/\",\"name\":\"SafLager\u2122 W-34\\\/70 - lievito Fermentis per birre dallo stile Weihenstephan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/saflager-w-34-70\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/saflager-w-34-70\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.bfldr.com\\\/G7S7MSWL\\\/at\\\/gzfvmgnhv7xwk8kh7xcct9k4\\\/SafAleTM_W-34-70-134_All_.jpg?auto=webp&format=png\",\"datePublished\":\"2024-07-30T08:29:41+00:00\",\"dateModified\":\"2026-09-02T13:51:59+00:00\",\"description\":\"Il lievito Fermentis SafLager\u2122 W-34\\\/70 \u00e8 ideale per la produzione di birre Weihenstephan, ma si adatta ad altri stili di birra, buon divertimento!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/saflager-w-34-70\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/saflager-w-34-70\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/saflager-w-34-70\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.bfldr.com\\\/G7S7MSWL\\\/at\\\/gzfvmgnhv7xwk8kh7xcct9k4\\\/SafAleTM_W-34-70-134_All_.jpg?auto=webp&format=png\",\"contentUrl\":\"https:\\\/\\\/cdn.bfldr.com\\\/G7S7MSWL\\\/at\\\/gzfvmgnhv7xwk8kh7xcct9k4\\\/SafAleTM_W-34-70-134_All_.jpg?auto=webp&format=png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/prodotto\\\/saflager-w-34-70\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fermentis.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beer &amp; brewing solutions\",\"item\":\"https:\\\/\\\/fermentis.com\\\/it\\\/fermentation\\\/beer-brewing-solutions-it\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Birra con lievito secco attivo\",\"item\":\"https:\\\/\\\/fermentis.com\\\/it\\\/fermentation\\\/beer-brewing-solutions-it\\\/active-dry-yeast-it\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"SafLager\u2122 W-34\\\/70\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/fermentis.com\\\/it\\\/\",\"name\":\"Fermentis\",\"description\":\"Un site utilisant WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fermentis.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/#organization\",\"name\":\"Fermentis\",\"url\":\"https:\\\/\\\/fermentis.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fermentis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-Fermentis-5.png\",\"contentUrl\":\"https:\\\/\\\/fermentis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Logo-Fermentis-5.png\",\"width\":308,\"height\":95,\"caption\":\"Fermentis\"},\"image\":{\"@id\":\"https:\\\/\\\/fermentis.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fermentis\",\"https:\\\/\\\/x.com\\\/fermentis\",\"https:\\\/\\\/www.instagram.com\\\/fermentisbylesaffre\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fermentis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCt_Lp3IZnUNXZeqSi6iiAdA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SafLager\u2122 W-34\/70 - lievito Fermentis per birre dallo stile Weihenstephan","description":"Il lievito Fermentis SafLager\u2122 W-34\/70 \u00e8 ideale per la produzione di birre Weihenstephan, ma si adatta ad altri stili di birra, buon divertimento!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/","og_locale":"it_IT","og_type":"article","og_title":"SafLager\u2122 W-34\/70","og_description":"Il lievito Fermentis SafLager\u2122 W-34\/70 \u00e8 ideale per la produzione di birre Weihenstephan, ma si adatta ad altri stili di birra, buon divertimento!","og_url":"https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/","og_site_name":"Fermentis","article_publisher":"https:\/\/www.facebook.com\/Fermentis","article_modified_time":"2026-09-02T13:51:59+00:00","og_image":[{"url":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/gzfvmgnhv7xwk8kh7xcct9k4\/SafAleTM_W-34-70-134_All_.jpg?auto=webp&format=png","width":1024,"height":1024,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@fermentis","twitter_misc":{"Prezzo":"","Disponibilit\u00e0":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/","url":"https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/","name":"SafLager\u2122 W-34\/70 - lievito Fermentis per birre dallo stile Weihenstephan","isPartOf":{"@id":"https:\/\/fermentis.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/#primaryimage"},"image":{"@id":"https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/gzfvmgnhv7xwk8kh7xcct9k4\/SafAleTM_W-34-70-134_All_.jpg?auto=webp&format=png","datePublished":"2024-07-30T08:29:41+00:00","dateModified":"2026-09-02T13:51:59+00:00","description":"Il lievito Fermentis SafLager\u2122 W-34\/70 \u00e8 ideale per la produzione di birre Weihenstephan, ma si adatta ad altri stili di birra, buon divertimento!","breadcrumb":{"@id":"https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/#primaryimage","url":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/gzfvmgnhv7xwk8kh7xcct9k4\/SafAleTM_W-34-70-134_All_.jpg?auto=webp&format=png","contentUrl":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/gzfvmgnhv7xwk8kh7xcct9k4\/SafAleTM_W-34-70-134_All_.jpg?auto=webp&format=png"},{"@type":"BreadcrumbList","@id":"https:\/\/fermentis.com\/it\/prodotto\/saflager-w-34-70\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fermentis.com\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti"},{"@type":"ListItem","position":3,"name":"Beer &amp; brewing solutions","item":"https:\/\/fermentis.com\/it\/fermentation\/beer-brewing-solutions-it\/"},{"@type":"ListItem","position":4,"name":"Birra con lievito secco attivo","item":"https:\/\/fermentis.com\/it\/fermentation\/beer-brewing-solutions-it\/active-dry-yeast-it\/"},{"@type":"ListItem","position":5,"name":"SafLager\u2122 W-34\/70"}]},{"@type":"WebSite","@id":"https:\/\/fermentis.com\/it\/#website","url":"https:\/\/fermentis.com\/it\/","name":"Fermentis","description":"Un site utilisant WordPress","publisher":{"@id":"https:\/\/fermentis.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fermentis.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/fermentis.com\/it\/#organization","name":"Fermentis","url":"https:\/\/fermentis.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fermentis.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/Logo-Fermentis-5.png","contentUrl":"https:\/\/fermentis.com\/wp-content\/uploads\/2021\/07\/Logo-Fermentis-5.png","width":308,"height":95,"caption":"Fermentis"},"image":{"@id":"https:\/\/fermentis.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fermentis","https:\/\/x.com\/fermentis","https:\/\/www.instagram.com\/fermentisbylesaffre\/","https:\/\/www.linkedin.com\/company\/fermentis\/","https:\/\/www.youtube.com\/channel\/UCt_Lp3IZnUNXZeqSi6iiAdA"]}]}},"fifu_image_url":"https:\/\/cdn.bfldr.com\/G7S7MSWL\/at\/gzfvmgnhv7xwk8kh7xcct9k4\/SafAleTM_W-34-70-134_All_.jpg?auto=webp&format=png","_links":{"self":[{"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/product\/41729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/comments?post=41729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/media\/738068"}],"wp:attachment":[{"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/media?parent=41729"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/product_brand?post=41729"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/product_cat?post=41729"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fermentis.com\/it\/wp-json\/wp\/v2\/product_tag?post=41729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}